{"id":46625,"date":"2024-07-08T08:04:07","date_gmt":"2024-07-08T06:04:07","guid":{"rendered":"https:\/\/ilcrogiuolo.it\/?p=46625"},"modified":"2024-07-02T17:21:00","modified_gmt":"2024-07-02T15:21:00","slug":"le-candele","status":"publish","type":"post","link":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/","title":{"rendered":"Le candele"},"content":{"rendered":"<p><strong>Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita:<\/strong> ricordate quando soffiaste la prima candelina sulla torta di compleanno\u2026 allora forse non ne eravate consapevoli, ma era il primo incanto che avreste eseguito nella vostra vita.<\/p>\n<p>Una fiamma, una speranza, un desiderio\u2026 e l\u2019attesa che si concretizzasse.<\/p>\n<p>In questa parte del testo tratteremo<strong> la magia del fuoco<\/strong> e <strong>le sue applicazioni<\/strong> mediante l\u2019impiego di candele.<\/p>\n<h3>L\u2019uso delle fiamme nella pratica spirituale, esoterica e religiosa \u00e8 fondamentale.<\/h3>\n<p>Accendere una candela o una fiamma significa automaticamente<strong> creare un legame con il divino<\/strong> che trascende il gesto in s\u00e9, aprendo un varco tra il mondo degli uomini e quello spirituale.<\/p>\n<p>I<strong> primi rudimenti della magia del fuoco sono presenti nella Bibbia<\/strong> dove si descrivono con estrema cura le modalit\u00e0 di alimentazione e preparazione delle <strong>lampade del tabernacolo<\/strong> nonch\u00e9 l\u2019importanza delle <strong>lampade nel culto del Dio d\u2019Israele<\/strong>.<\/p>\n<p>L\u2019Esoterismo ha adottato l&#8217;<strong>uso delle candele dalla ritualistica ebraica e cristiana<\/strong>. <strong>La candela medesima viene a rappresentare l\u2019anima<\/strong> e <strong>la fiamma rappresenta la preghiera<\/strong> che si eleva verso Dio o una sua diretta emanazione. La tradizione vuole che la preghiera duri il tempo della fiamma stessa della candela. Pi\u00f9 la fiamma ha durata, maggiormente forte sar\u00e0 la richiesta. Questa idea \u00e8 presente anche nel concetto che sta alla base delle<strong> novene cattoliche<\/strong>. Le novene sono delle preghiere che vengono<strong> recitate per nove giorni consecutivi<\/strong>. Ogni giorno si recitano le orazioni d\u2019obbligo e si accende una candela.<\/p>\n<p>Nella simbologia della candela sono inoltre presenti <strong>i quattro elementi che reggono il cosmo<\/strong>: <strong>la terra nella cera<\/strong>, <strong>il fuoco nella fiamma<\/strong>, <strong>l\u2019acqua nello sciogliersi della cera<\/strong> e <strong>l\u2019aria nel fumo<\/strong> che sale dalla combustione.<\/p>\n<p>L\u2019impiego delle candele, nelle varie tradizioni esoteriche, segue<strong> regole ben precise<\/strong> e nel corso degli anni i sacerdoti hanno elaborato uno schema di impiego che si rif\u00e0 a una tradizione ormai codificata e accettata da tutti.<\/p>\n<p>Nella ritualistica<strong> le candele impiegate vengono \u201cvestite\u201d<\/strong>, ossia unte con un <strong>olio esoterico<\/strong> appropriato allo scopo che si intende perseguire. L\u2019unzione delle candele deve avvenire in un certo modo, non \u00e8 sufficiente bagnare la candela con l\u2019olio giusto, occorre seguire alcune indicazioni di base, che potrete trovare nel nostro <strong><a href=\"https:\/\/ilcrogiuolo.it\/it\/blog\/unzione-delle-candele\/\">Blog<\/a>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2034,1866,1970,1854],"tags":[],"class_list":["post-46625","post","type-post","status-publish","format-standard","hentry","category-le-candele","category-ricettario","category-voodoo","category-spiritismo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le candele - Il Crogiuolo<\/title>\n<meta name=\"description\" content=\"Le candele Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita: ricordate quando\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le candele - Il Crogiuolo\" \/>\n<meta property=\"og:description\" content=\"Le candele Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita: ricordate quando\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Crogiuolo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Il-Crogiuolo-681876418491758\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T06:04:07+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#\\\/schema\\\/person\\\/78221c099249d3b54e2633f580e79cc4\"},\"headline\":\"Le candele\",\"datePublished\":\"2024-07-08T06:04:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/\"},\"wordCount\":385,\"publisher\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#organization\"},\"articleSection\":[\"Le Candele\",\"Ricettario\",\"Rituali e tradizioni Voodoo\",\"Spiritismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/\",\"url\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/\",\"name\":\"Le candele - Il Crogiuolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#website\"},\"datePublished\":\"2024-07-08T06:04:07+00:00\",\"description\":\"Le candele Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita: ricordate quando\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/blog\\\/le-candele\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le candele\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/\",\"name\":\"Il Crogiuolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#organization\",\"name\":\"Il Crogiuolo\",\"url\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ilcrogiuolo.it\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/ilcrogiuolo.it\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo.png\",\"width\":200,\"height\":49,\"caption\":\"Il Crogiuolo\"},\"image\":{\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Il-Crogiuolo-681876418491758\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ilcrogiuolo.it\\\/it\\\/#\\\/schema\\\/person\\\/78221c099249d3b54e2633f580e79cc4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c465261d61906bf4c7e82a8d37c043e6254f20ed79214044f59a94ca28ef3157?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c465261d61906bf4c7e82a8d37c043e6254f20ed79214044f59a94ca28ef3157?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c465261d61906bf4c7e82a8d37c043e6254f20ed79214044f59a94ca28ef3157?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le candele - Il Crogiuolo","description":"Le candele Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita: ricordate quando","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/","og_locale":"it_IT","og_type":"article","og_title":"Le candele - Il Crogiuolo","og_description":"Le candele Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita: ricordate quando","og_url":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/","og_site_name":"Il Crogiuolo","article_publisher":"https:\/\/www.facebook.com\/Il-Crogiuolo-681876418491758","article_published_time":"2024-07-08T06:04:07+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/#article","isPartOf":{"@id":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/"},"author":{"name":"admin","@id":"https:\/\/ilcrogiuolo.it\/it\/#\/schema\/person\/78221c099249d3b54e2633f580e79cc4"},"headline":"Le candele","datePublished":"2024-07-08T06:04:07+00:00","mainEntityOfPage":{"@id":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/"},"wordCount":385,"publisher":{"@id":"https:\/\/ilcrogiuolo.it\/it\/#organization"},"articleSection":["Le Candele","Ricettario","Rituali e tradizioni Voodoo","Spiritismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/","url":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/","name":"Le candele - Il Crogiuolo","isPartOf":{"@id":"https:\/\/ilcrogiuolo.it\/it\/#website"},"datePublished":"2024-07-08T06:04:07+00:00","description":"Le candele Dei quattro elementi il Fuoco \u00e8 sicuramente quello maggiormente impiegato in Esoterismo e che ci accompagna fin dal primo anno di vita: ricordate quando","breadcrumb":{"@id":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ilcrogiuolo.it\/it\/blog\/le-candele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ilcrogiuolo.it\/it\/"},{"@type":"ListItem","position":2,"name":"Le candele"}]},{"@type":"WebSite","@id":"https:\/\/ilcrogiuolo.it\/it\/#website","url":"https:\/\/ilcrogiuolo.it\/it\/","name":"Il Crogiuolo","description":"","publisher":{"@id":"https:\/\/ilcrogiuolo.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ilcrogiuolo.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ilcrogiuolo.it\/it\/#organization","name":"Il Crogiuolo","url":"https:\/\/ilcrogiuolo.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ilcrogiuolo.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ilcrogiuolo.it\/wp-content\/uploads\/2020\/04\/logo.png","contentUrl":"https:\/\/ilcrogiuolo.it\/wp-content\/uploads\/2020\/04\/logo.png","width":200,"height":49,"caption":"Il Crogiuolo"},"image":{"@id":"https:\/\/ilcrogiuolo.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Il-Crogiuolo-681876418491758"]},{"@type":"Person","@id":"https:\/\/ilcrogiuolo.it\/it\/#\/schema\/person\/78221c099249d3b54e2633f580e79cc4","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c465261d61906bf4c7e82a8d37c043e6254f20ed79214044f59a94ca28ef3157?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c465261d61906bf4c7e82a8d37c043e6254f20ed79214044f59a94ca28ef3157?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c465261d61906bf4c7e82a8d37c043e6254f20ed79214044f59a94ca28ef3157?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/posts\/46625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/comments?post=46625"}],"version-history":[{"count":1,"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/posts\/46625\/revisions"}],"predecessor-version":[{"id":46626,"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/posts\/46625\/revisions\/46626"}],"wp:attachment":[{"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/media?parent=46625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/categories?post=46625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ilcrogiuolo.it\/it\/wp-json\/wp\/v2\/tags?post=46625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}